{"id":735,"date":"2020-09-10T15:55:06","date_gmt":"2020-09-10T13:55:06","guid":{"rendered":"https:\/\/barcelonacolours.com\/extraescolares\/?post_type=listing&#038;p=735"},"modified":"2020-09-14T21:42:40","modified_gmt":"2020-09-14T19:42:40","slug":"long-school","status":"publish","type":"listing","link":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/","title":{"rendered":"LONG SCHOOL"},"content":{"rendered":"<p>Long School apuesta por el Skateboard en todas sus modalidades como un deporte con todas sus letras y en may\u00fascula. Y como en todo otro deporte, la base reside en los m\u00e1s peque\u00f1os.Es por eso que ofrecemos un servicio de clases dedicadas exclusivamente a ni\u00f1os y ni\u00f1as, donde se les pueda dedicar atenci\u00f3n exclusiva para poder introducirlos\/las en nuestro deporte o ayudarles a mejorar si ya han empezado.<\/p>\n<h1><strong>EXTRAESCOLARES DE SKATEBOARD<\/strong><\/h1>\n<p>Las Clases Extraescolares de Long School son pues una opci\u00f3n perfecta para que ni\u00f1os, ni\u00f1as y adolescentes de diversas edades puedan dedicar un tiempo a la autosuperaci\u00f3n en el deporte de forma segura cada fin de semana.<\/p>\n<p><strong>Edades:<\/strong> de 5 a 14 a\u00f1os<\/p>\n<p><strong>Horarios:<\/strong><\/p>\n<div>Opci\u00f3n 1: Martes y jueves de 17h30 a 18h30;<\/div>\n<div>Opci\u00f3n 2: S\u00e1bados de 10h a 11h30<\/div>\n<div><\/div>\n<div>Consulta toda la informaci\u00f3n en nuestra web<\/div>\n<div><\/div>\n","protected":false},"author":7,"featured_media":736,"comment_status":"closed","ping_status":"closed","template":"","listing-category":[23],"list-tags":[],"location":[],"class_list":["post-735","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing-category-deporte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LONG SCHOOL - Extraescolares Barcelonacolours<\/title>\n<meta name=\"description\" content=\"Si buscas una extraescolar para ni\u00f1os de skateboard en Barcelona en Long School ofrecen clases entre semana y fines de semana para ni\u00f1os\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LONG SCHOOL - Extraescolares Barcelonacolours\" \/>\n<meta property=\"og:description\" content=\"Si buscas una extraescolar para ni\u00f1os de skateboard en Barcelona en Long School ofrecen clases entre semana y fines de semana para ni\u00f1os\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/\" \/>\n<meta property=\"og:site_name\" content=\"Extraescolares Barcelonacolours\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-14T19:42:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2020\/09\/extraescolar-skateboard-barcelona-longschool1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/long-school\\\/\",\"url\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/long-school\\\/\",\"name\":\"LONG SCHOOL - Extraescolares Barcelonacolours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/long-school\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/long-school\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/extraescolar-skateboard-barcelona-longschool1.jpg\",\"datePublished\":\"2020-09-10T13:55:06+00:00\",\"dateModified\":\"2020-09-14T19:42:40+00:00\",\"description\":\"Si buscas una extraescolar para ni\u00f1os de skateboard en Barcelona en Long School ofrecen clases entre semana y fines de semana para ni\u00f1os\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/long-school\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/long-school\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/long-school\\\/#primaryimage\",\"url\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/extraescolar-skateboard-barcelona-longschool1.jpg\",\"contentUrl\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/extraescolar-skateboard-barcelona-longschool1.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/long-school\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LONG SCHOOL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/#website\",\"url\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/\",\"name\":\"Extraescolares Barcelonacolours\",\"description\":\"By Barcelona Colours\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LONG SCHOOL - Extraescolares Barcelonacolours","description":"Si buscas una extraescolar para ni\u00f1os de skateboard en Barcelona en Long School ofrecen clases entre semana y fines de semana para ni\u00f1os","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/","og_locale":"es_ES","og_type":"article","og_title":"LONG SCHOOL - Extraescolares Barcelonacolours","og_description":"Si buscas una extraescolar para ni\u00f1os de skateboard en Barcelona en Long School ofrecen clases entre semana y fines de semana para ni\u00f1os","og_url":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/","og_site_name":"Extraescolares Barcelonacolours","article_modified_time":"2020-09-14T19:42:40+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2020\/09\/extraescolar-skateboard-barcelona-longschool1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/","url":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/","name":"LONG SCHOOL - Extraescolares Barcelonacolours","isPartOf":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/#website"},"primaryImageOfPage":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/#primaryimage"},"image":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/#primaryimage"},"thumbnailUrl":"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2020\/09\/extraescolar-skateboard-barcelona-longschool1.jpg","datePublished":"2020-09-10T13:55:06+00:00","dateModified":"2020-09-14T19:42:40+00:00","description":"Si buscas una extraescolar para ni\u00f1os de skateboard en Barcelona en Long School ofrecen clases entre semana y fines de semana para ni\u00f1os","breadcrumb":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/#primaryimage","url":"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2020\/09\/extraescolar-skateboard-barcelona-longschool1.jpg","contentUrl":"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2020\/09\/extraescolar-skateboard-barcelona-longschool1.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/long-school\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/barcelonacolours.com\/extraescolares\/"},{"@type":"ListItem","position":2,"name":"LONG SCHOOL"}]},{"@type":"WebSite","@id":"https:\/\/barcelonacolours.com\/extraescolares\/#website","url":"https:\/\/barcelonacolours.com\/extraescolares\/","name":"Extraescolares Barcelonacolours","description":"By Barcelona Colours","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barcelonacolours.com\/extraescolares\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/listing\/735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/comments?post=735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/media\/736"}],"wp:attachment":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/media?parent=735"}],"wp:term":[{"taxonomy":"listing-category","embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/listing-category?post=735"},{"taxonomy":"list-tags","embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/list-tags?post=735"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/location?post=735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}