{"id":842,"date":"2021-09-19T23:29:01","date_gmt":"2021-09-19T21:29:01","guid":{"rendered":"https:\/\/barcelonacolours.com\/extraescolares\/?post_type=listing&#038;p=842"},"modified":"2021-09-19T23:36:02","modified_gmt":"2021-09-19T21:36:02","slug":"my-little-van-gogh","status":"publish","type":"listing","link":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/","title":{"rendered":"MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE"},"content":{"rendered":"<h2 class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s3_HNI o3ifjf---location-4-BODY\" aria-hidden=\"false\" data-hook=\"description-title\">EXTRAESCOLAR DE ARTE Y CREATIVIDAD<\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-963\" src=\"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/extraescolares_my_little_van_gogh_barcelona3.png\" alt=\"\" width=\"700\" height=\"401\" srcset=\"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/extraescolares_my_little_van_gogh_barcelona3.png 700w, https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/extraescolares_my_little_van_gogh_barcelona3-300x172.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\">Extraescolar para peques de 6 a 9 a\u00f1os (1ero, 2do y 3ero primaria), es posible aceptar peques de 5 a\u00f1os que est\u00e9n ya en primaria. Todas las actividades se realizan en ingl\u00e9s o castellano. El programa es anual y cada mes exploramos un tema diferente y propondremos 2 \u00f3 3 actividades por taller.<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\">Cada semana descubriremos nuevos proyectos de modelado, arte cooperativo, juego sensorial, process art, tinkering o STEAM (por su siglas en ingl\u00e9s ciencia, tecnolog\u00eda, ingenier\u00eda, arte y matem\u00e1ticas). Les proponemos m\u00faltiples posibilidades sobre c\u00f3mo se pueden utilizar los materiales y herramientas. Se dan ideas de proyectos pero se les anima a experimentar y descubrir.<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\"><strong> Precio<\/strong>: 50\u20ac\/mes, incluye todos los materiales. Si pagas el trimestre por adelantado son 135 euros.<\/p>\n<h2 aria-hidden=\"false\" data-hook=\"description\"><strong>ART CLUB DE 1 A 3 A\u00d1OS Y DE 4 A 7 A\u00d1OS<\/strong><\/h2>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-964\" src=\"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/extraescolares_my_little_van_gogh_barcelona5.png\" alt=\"\" width=\"700\" height=\"434\" srcset=\"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/extraescolares_my_little_van_gogh_barcelona5.png 700w, https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/extraescolares_my_little_van_gogh_barcelona5-300x186.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\">Este es un taller grupal en el que los adultos acompa\u00f1amos a los ni\u00f1os en su recorrido y exploramos, creamos y nos ensuciamos juntos.\u00a0 Compuesto por estaciones de juego sensorial (agua, arena, arroz, harina, piezas sueltas&#8230;), proyectos con pintura (estampar, pintar, collage&#8230;), modelado (plastilina, arcilla, barro&#8230;), arte cooperativo (pintar con todo el cuerpo y en grandes espacios) y exploraci\u00f3n de la luz (descubrir los colores, la luz y la sombra).<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\">El peque decide qu\u00e9 actividades quiere hacer y por cu\u00e1nto tiempo. No es una clase dirigida, cada uno explora en funci\u00f3n de sus intereses y ritmo. Todas las actividades est\u00e1n disponibles al iniciar el taller, y cada una es una propuesta a descubrir un material o t\u00e9cnica diferente.<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\">Programa: trabajamos por trimestre y cada taller es diferente, siempre siguiendo la misma metodolog\u00eda.<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\"><strong>Precios y Packs:<\/strong> Pod\u00e9is comprar 12 sesiones por 15 euros cada una o 6 por 18 euros cada una. Con los packs tienes la flexibilidad de venir a cualquier clase y recibir descuentos.<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\"><strong>Edades:<\/strong> De 15 \u00f3 18 meses el grupo de peques y de 4 a 7 a\u00f1os el otro grupo.<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\"><strong>Aforo<\/strong>: entre 6 y 10 familias.<\/p>\n<h2 aria-hidden=\"false\" data-hook=\"description\">MINI CAMPUS<\/h2>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\">Ahora tus peques pueden disfrutar de tres horas llena de creatividad, arte y movimiento. Un plan perfecto para quienes quieren tener un finde diferente. Es como venir a un casal en cualquier momento del a\u00f1o \u00bfMola, no?<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\">Cada Mini-Campus tiene una agenda propia para sorprender a nuestros peque\u00f1os artistas. Los peques participar\u00e1n sin adulto acompa\u00f1ante, nosotras nos haremos cargo de ellos durante todo el taller<\/p>\n<p class=\"s1FBdq o18H-b---typography-11-runningText o18H-b---priority-7-primary s2GijN o3cMdy---location-4-BODY s1PSYu\" aria-hidden=\"false\" data-hook=\"description\"><strong>\u00bfCu\u00e1ndo son?<\/strong> Ocurren dos veces al mes, un domingo o un s\u00e1bado, en la ma\u00f1ana (10:30) y en la tarde (14:30).<\/p>\n<p aria-hidden=\"false\" data-hook=\"description\"><em><strong>TODA LA INFORMACI\u00d3N EN NUESTRA WEB<\/strong><\/em><\/p>\n","protected":false},"author":37,"featured_media":961,"comment_status":"closed","ping_status":"closed","template":"","listing-category":[14,29],"list-tags":[],"location":[49],"class_list":["post-842","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing-category-artisticos","listing-category-idioma","location-gracia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE - Extraescolares Barcelonacolours<\/title>\n<meta name=\"description\" content=\"Las mejores extraescolares de arte en ingl\u00e9s y castellano de Barcelona para ni\u00f1os de 1 a 7 a\u00f1os, pintura, madera, barro, juegos de luz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE - Extraescolares Barcelonacolours\" \/>\n<meta property=\"og:description\" content=\"Las mejores extraescolares de arte en ingl\u00e9s y castellano de Barcelona para ni\u00f1os de 1 a 7 a\u00f1os, pintura, madera, barro, juegos de luz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/\" \/>\n<meta property=\"og:site_name\" content=\"Extraescolares Barcelonacolours\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-19T21:36:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/logo_my_little_van_gogh_barcelona_extraescolares.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/my-little-van-gogh\\\/\",\"url\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/my-little-van-gogh\\\/\",\"name\":\"MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE - Extraescolares Barcelonacolours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/my-little-van-gogh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/my-little-van-gogh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_my_little_van_gogh_barcelona_extraescolares.jpeg\",\"datePublished\":\"2021-09-19T21:29:01+00:00\",\"dateModified\":\"2021-09-19T21:36:02+00:00\",\"description\":\"Las mejores extraescolares de arte en ingl\u00e9s y castellano de Barcelona para ni\u00f1os de 1 a 7 a\u00f1os, pintura, madera, barro, juegos de luz\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/my-little-van-gogh\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/my-little-van-gogh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/my-little-van-gogh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_my_little_van_gogh_barcelona_extraescolares.jpeg\",\"contentUrl\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_my_little_van_gogh_barcelona_extraescolares.jpeg\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/actividad\\\/my-little-van-gogh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/#website\",\"url\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/\",\"name\":\"Extraescolares Barcelonacolours\",\"description\":\"By Barcelona Colours\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE - Extraescolares Barcelonacolours","description":"Las mejores extraescolares de arte en ingl\u00e9s y castellano de Barcelona para ni\u00f1os de 1 a 7 a\u00f1os, pintura, madera, barro, juegos de luz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/","og_locale":"es_ES","og_type":"article","og_title":"MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE - Extraescolares Barcelonacolours","og_description":"Las mejores extraescolares de arte en ingl\u00e9s y castellano de Barcelona para ni\u00f1os de 1 a 7 a\u00f1os, pintura, madera, barro, juegos de luz","og_url":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/","og_site_name":"Extraescolares Barcelonacolours","article_modified_time":"2021-09-19T21:36:02+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/logo_my_little_van_gogh_barcelona_extraescolares.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/","url":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/","name":"MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE - Extraescolares Barcelonacolours","isPartOf":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/#website"},"primaryImageOfPage":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/#primaryimage"},"image":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/#primaryimage"},"thumbnailUrl":"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/logo_my_little_van_gogh_barcelona_extraescolares.jpeg","datePublished":"2021-09-19T21:29:01+00:00","dateModified":"2021-09-19T21:36:02+00:00","description":"Las mejores extraescolares de arte en ingl\u00e9s y castellano de Barcelona para ni\u00f1os de 1 a 7 a\u00f1os, pintura, madera, barro, juegos de luz","breadcrumb":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/#primaryimage","url":"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/logo_my_little_van_gogh_barcelona_extraescolares.jpeg","contentUrl":"https:\/\/barcelonacolours.com\/extraescolares\/wp-content\/uploads\/2021\/02\/logo_my_little_van_gogh_barcelona_extraescolares.jpeg","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/barcelonacolours.com\/extraescolares\/actividad\/my-little-van-gogh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/barcelonacolours.com\/extraescolares\/"},{"@type":"ListItem","position":2,"name":"MY LITTLE VAN GOGH EXTRAESCOLARES DE ARTE"}]},{"@type":"WebSite","@id":"https:\/\/barcelonacolours.com\/extraescolares\/#website","url":"https:\/\/barcelonacolours.com\/extraescolares\/","name":"Extraescolares Barcelonacolours","description":"By Barcelona Colours","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barcelonacolours.com\/extraescolares\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/listing\/842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/comments?post=842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/media\/961"}],"wp:attachment":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/media?parent=842"}],"wp:term":[{"taxonomy":"listing-category","embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/listing-category?post=842"},{"taxonomy":"list-tags","embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/list-tags?post=842"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/location?post=842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}