{"id":43,"count":11,"description":"","link":"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/","name":"Sarri\u00e0 Sant Gervasi","slug":"sarria-sant-gervasi","taxonomy":"location","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sarri\u00e0 Sant Gervasi archivos - Extraescolares Barcelonacolours<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sarri\u00e0 Sant Gervasi archivos - Extraescolares Barcelonacolours\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/\" \/>\n<meta property=\"og:site_name\" content=\"Extraescolares Barcelonacolours\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/localizacion\\\/sarria-sant-gervasi\\\/\",\"url\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/localizacion\\\/sarria-sant-gervasi\\\/\",\"name\":\"Sarri\u00e0 Sant Gervasi archivos - Extraescolares Barcelonacolours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/localizacion\\\/sarria-sant-gervasi\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/localizacion\\\/sarria-sant-gervasi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sarri\u00e0 Sant Gervasi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/#website\",\"url\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/\",\"name\":\"Extraescolares Barcelonacolours\",\"description\":\"By Barcelona Colours\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/barcelonacolours.com\\\/extraescolares\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sarri\u00e0 Sant Gervasi archivos - Extraescolares Barcelonacolours","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/","og_locale":"es_ES","og_type":"article","og_title":"Sarri\u00e0 Sant Gervasi archivos - Extraescolares Barcelonacolours","og_url":"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/","og_site_name":"Extraescolares Barcelonacolours","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/","url":"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/","name":"Sarri\u00e0 Sant Gervasi archivos - Extraescolares Barcelonacolours","isPartOf":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/#website"},"breadcrumb":{"@id":"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/barcelonacolours.com\/extraescolares\/localizacion\/sarria-sant-gervasi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/barcelonacolours.com\/extraescolares\/"},{"@type":"ListItem","position":2,"name":"Sarri\u00e0 Sant Gervasi"}]},{"@type":"WebSite","@id":"https:\/\/barcelonacolours.com\/extraescolares\/#website","url":"https:\/\/barcelonacolours.com\/extraescolares\/","name":"Extraescolares Barcelonacolours","description":"By Barcelona Colours","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barcelonacolours.com\/extraescolares\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/location\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/taxonomies\/location"}],"wp:post_type":[{"href":"https:\/\/barcelonacolours.com\/extraescolares\/wp-json\/wp\/v2\/listing?location=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}